{"id":3307,"date":"2017-02-16T08:28:49","date_gmt":"2017-02-16T08:28:49","guid":{"rendered":"http:\/\/www.mariovitoria.com\/?p=3307"},"modified":"2018-02-16T08:37:42","modified_gmt":"2018-02-16T08:37:42","slug":"cover-art-for-the-book-demodiversidad-imaginar-nuvens-posibilidades-democraticas-boaventura-sousa-santos-jose-manuel-mendes-ed-akal-2017","status":"publish","type":"post","link":"https:\/\/www.mariovitoria.com\/en\/participacoes-especiais\/cover-art-for-the-book-demodiversidad-imaginar-nuvens-posibilidades-democraticas-boaventura-sousa-santos-jose-manuel-mendes-ed-akal-2017\/","title":{"rendered":"Cover Art for the Book Demodiversidad. Imaginar nuvens posibilidades democr\u00e1ticas, Boaventura de Sousa Santos e Jos\u00e9 Manuel Mendes, Ed. Akal"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":3311,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-3307","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-participacoes-especiais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>M\u00e1rio Vit\u00f3ria -  Cover Art for the Book Demodiversidad. Imaginar nuvens posibilidades democr\u00e1ticas, Boaventura de Sousa Santos e Jos\u00e9 Manuel Mendes, Ed. Akal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mariovitoria.com\/participacoes-especiais\/cover-art-for-the-book-demodiversidad-imaginar-nuvens-posibilidades-democraticas-boaventura-sousa-santos-jose-manuel-mendes-ed-akal-2017\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e1rio Vit\u00f3ria - [:pt]Cria\u00e7\u00e3o de capa para o Livro Demodiversidad. Imaginar nuvens posibilidades democr\u00e1ticas, Boaventura de Sousa Santos e Jos\u00e9 Manuel Mendes, Ed. Akal[:en] Cover Art for the Book Demodiversidad. Imaginar nuvens posibilidades democr\u00e1ticas, Boaventura de Sousa Santos e Jos\u00e9 Manuel Mendes, Ed. Akal[:]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mariovitoria.com\/participacoes-especiais\/cover-art-for-the-book-demodiversidad-imaginar-nuvens-posibilidades-democraticas-boaventura-sousa-santos-jose-manuel-mendes-ed-akal-2017\/\" \/>\n<meta property=\"og:site_name\" content=\"M\u00e1rio Vit\u00f3ria\" \/>\n<meta property=\"article:published_time\" content=\"2017-02-16T08:28:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-02-16T08:37:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mariovitoria.com\/wp-content\/uploads\/2017\/02\/MV..jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"829\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"joana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"joana\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.mariovitoria.com\/participacoes-especiais\/cover-art-for-the-book-demodiversidad-imaginar-nuvens-posibilidades-democraticas-boaventura-sousa-santos-jose-manuel-mendes-ed-akal-2017\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.mariovitoria.com\/participacoes-especiais\/cover-art-for-the-book-demodiversidad-imaginar-nuvens-posibilidades-democraticas-boaventura-sousa-santos-jose-manuel-mendes-ed-akal-2017\/\"},\"author\":{\"name\":\"joana\",\"@id\":\"https:\/\/www.mariovitoria.com\/#\/schema\/person\/3e39fc7c3dfd691c4f16c3bf2c402146\"},\"headline\":\"Cover Art for the Book Demodiversidad. Imaginar nuvens posibilidades democr\u00e1ticas, Boaventura de Sousa Santos e Jos\u00e9 Manuel Mendes, Ed. Akal\",\"datePublished\":\"2017-02-16T08:28:49+00:00\",\"dateModified\":\"2018-02-16T08:37:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.mariovitoria.com\/participacoes-especiais\/cover-art-for-the-book-demodiversidad-imaginar-nuvens-posibilidades-democraticas-boaventura-sousa-santos-jose-manuel-mendes-ed-akal-2017\/\"},\"wordCount\":46,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.mariovitoria.com\/#\/schema\/person\/c6a74ef60d3e174cc1af41fabf008e87\"},\"articleSection\":[\"Special Participations\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.mariovitoria.com\/participacoes-especiais\/cover-art-for-the-book-demodiversidad-imaginar-nuvens-posibilidades-democraticas-boaventura-sousa-santos-jose-manuel-mendes-ed-akal-2017\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.mariovitoria.com\/participacoes-especiais\/cover-art-for-the-book-demodiversidad-imaginar-nuvens-posibilidades-democraticas-boaventura-sousa-santos-jose-manuel-mendes-ed-akal-2017\/\",\"url\":\"https:\/\/www.mariovitoria.com\/participacoes-especiais\/cover-art-for-the-book-demodiversidad-imaginar-nuvens-posibilidades-democraticas-boaventura-sousa-santos-jose-manuel-mendes-ed-akal-2017\/\",\"name\":\"M\u00e1rio Vit\u00f3ria - [:pt]Cria\u00e7\u00e3o de capa para o Livro Demodiversidad. Imaginar nuvens posibilidades democr\u00e1ticas, Boaventura de Sousa Santos e Jos\u00e9 Manuel Mendes, Ed. Akal[:en] Cover Art for the Book Demodiversidad. Imaginar nuvens posibilidades democr\u00e1ticas, Boaventura de Sousa Santos e Jos\u00e9 Manuel Mendes, Ed. Akal[:]\",\"isPartOf\":{\"@id\":\"https:\/\/www.mariovitoria.com\/#website\"},\"datePublished\":\"2017-02-16T08:28:49+00:00\",\"dateModified\":\"2018-02-16T08:37:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.mariovitoria.com\/participacoes-especiais\/cover-art-for-the-book-demodiversidad-imaginar-nuvens-posibilidades-democraticas-boaventura-sousa-santos-jose-manuel-mendes-ed-akal-2017\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.mariovitoria.com\/participacoes-especiais\/cover-art-for-the-book-demodiversidad-imaginar-nuvens-posibilidades-democraticas-boaventura-sousa-santos-jose-manuel-mendes-ed-akal-2017\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.mariovitoria.com\/participacoes-especiais\/cover-art-for-the-book-demodiversidad-imaginar-nuvens-posibilidades-democraticas-boaventura-sousa-santos-jose-manuel-mendes-ed-akal-2017\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.mariovitoria.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cria\u00e7\u00e3o de capa para o Livro Demodiversidad. Imaginar nuvens posibilidades democr\u00e1ticas, Boaventura de Sousa Santos e Jos\u00e9 Manuel Mendes, Ed. Akal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.mariovitoria.com\/#website\",\"url\":\"https:\/\/www.mariovitoria.com\/\",\"name\":\"M\u00e1rio Vit\u00f3ria\",\"description\":\"Artista Pl\u00e1stico\",\"publisher\":{\"@id\":\"https:\/\/www.mariovitoria.com\/#\/schema\/person\/c6a74ef60d3e174cc1af41fabf008e87\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.mariovitoria.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/www.mariovitoria.com\/#\/schema\/person\/c6a74ef60d3e174cc1af41fabf008e87\",\"name\":\"vitoria\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.mariovitoria.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ee633eb0e52b9e9665a034b3c1298ee0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ee633eb0e52b9e9665a034b3c1298ee0?s=96&d=mm&r=g\",\"caption\":\"vitoria\"},\"logo\":{\"@id\":\"https:\/\/www.mariovitoria.com\/#\/schema\/person\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.mariovitoria.com\/#\/schema\/person\/3e39fc7c3dfd691c4f16c3bf2c402146\",\"name\":\"joana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.mariovitoria.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/819ee59d51c0110bd6d4581a39403f35?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/819ee59d51c0110bd6d4581a39403f35?s=96&d=mm&r=g\",\"caption\":\"joana\"},\"url\":\"https:\/\/www.mariovitoria.com\/en\/author\/joana\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e1rio Vit\u00f3ria - [:pt]Cria\u00e7\u00e3o de capa para o Livro Demodiversidad. Imaginar nuvens posibilidades democr\u00e1ticas, Boaventura de Sousa Santos e Jos\u00e9 Manuel Mendes, Ed. Akal[:en] Cover Art for the Book Demodiversidad. Imaginar nuvens posibilidades democr\u00e1ticas, Boaventura de Sousa Santos e Jos\u00e9 Manuel Mendes, Ed. Akal[:]","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mariovitoria.com\/participacoes-especiais\/cover-art-for-the-book-demodiversidad-imaginar-nuvens-posibilidades-democraticas-boaventura-sousa-santos-jose-manuel-mendes-ed-akal-2017\/","og_locale":"en_US","og_type":"article","og_title":"M\u00e1rio Vit\u00f3ria - [:pt]Cria\u00e7\u00e3o de capa para o Livro Demodiversidad. Imaginar nuvens posibilidades democr\u00e1ticas, Boaventura de Sousa Santos e Jos\u00e9 Manuel Mendes, Ed. Akal[:en] Cover Art for the Book Demodiversidad. Imaginar nuvens posibilidades democr\u00e1ticas, Boaventura de Sousa Santos e Jos\u00e9 Manuel Mendes, Ed. Akal[:]","og_url":"https:\/\/www.mariovitoria.com\/participacoes-especiais\/cover-art-for-the-book-demodiversidad-imaginar-nuvens-posibilidades-democraticas-boaventura-sousa-santos-jose-manuel-mendes-ed-akal-2017\/","og_site_name":"M\u00e1rio Vit\u00f3ria","article_published_time":"2017-02-16T08:28:49+00:00","article_modified_time":"2018-02-16T08:37:42+00:00","og_image":[{"width":500,"height":829,"url":"https:\/\/www.mariovitoria.com\/wp-content\/uploads\/2017\/02\/MV..jpg","type":"image\/jpeg"}],"author":"joana","twitter_card":"summary_large_image","twitter_misc":{"Written by":"joana"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mariovitoria.com\/participacoes-especiais\/cover-art-for-the-book-demodiversidad-imaginar-nuvens-posibilidades-democraticas-boaventura-sousa-santos-jose-manuel-mendes-ed-akal-2017\/#article","isPartOf":{"@id":"https:\/\/www.mariovitoria.com\/participacoes-especiais\/cover-art-for-the-book-demodiversidad-imaginar-nuvens-posibilidades-democraticas-boaventura-sousa-santos-jose-manuel-mendes-ed-akal-2017\/"},"author":{"name":"joana","@id":"https:\/\/www.mariovitoria.com\/#\/schema\/person\/3e39fc7c3dfd691c4f16c3bf2c402146"},"headline":"Cover Art for the Book Demodiversidad. Imaginar nuvens posibilidades democr\u00e1ticas, Boaventura de Sousa Santos e Jos\u00e9 Manuel Mendes, Ed. Akal","datePublished":"2017-02-16T08:28:49+00:00","dateModified":"2018-02-16T08:37:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mariovitoria.com\/participacoes-especiais\/cover-art-for-the-book-demodiversidad-imaginar-nuvens-posibilidades-democraticas-boaventura-sousa-santos-jose-manuel-mendes-ed-akal-2017\/"},"wordCount":46,"commentCount":0,"publisher":{"@id":"https:\/\/www.mariovitoria.com\/#\/schema\/person\/c6a74ef60d3e174cc1af41fabf008e87"},"articleSection":["Special Participations"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.mariovitoria.com\/participacoes-especiais\/cover-art-for-the-book-demodiversidad-imaginar-nuvens-posibilidades-democraticas-boaventura-sousa-santos-jose-manuel-mendes-ed-akal-2017\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.mariovitoria.com\/participacoes-especiais\/cover-art-for-the-book-demodiversidad-imaginar-nuvens-posibilidades-democraticas-boaventura-sousa-santos-jose-manuel-mendes-ed-akal-2017\/","url":"https:\/\/www.mariovitoria.com\/participacoes-especiais\/cover-art-for-the-book-demodiversidad-imaginar-nuvens-posibilidades-democraticas-boaventura-sousa-santos-jose-manuel-mendes-ed-akal-2017\/","name":"M\u00e1rio Vit\u00f3ria - [:pt]Cria\u00e7\u00e3o de capa para o Livro Demodiversidad. Imaginar nuvens posibilidades democr\u00e1ticas, Boaventura de Sousa Santos e Jos\u00e9 Manuel Mendes, Ed. Akal[:en] Cover Art for the Book Demodiversidad. Imaginar nuvens posibilidades democr\u00e1ticas, Boaventura de Sousa Santos e Jos\u00e9 Manuel Mendes, Ed. Akal[:]","isPartOf":{"@id":"https:\/\/www.mariovitoria.com\/#website"},"datePublished":"2017-02-16T08:28:49+00:00","dateModified":"2018-02-16T08:37:42+00:00","breadcrumb":{"@id":"https:\/\/www.mariovitoria.com\/participacoes-especiais\/cover-art-for-the-book-demodiversidad-imaginar-nuvens-posibilidades-democraticas-boaventura-sousa-santos-jose-manuel-mendes-ed-akal-2017\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mariovitoria.com\/participacoes-especiais\/cover-art-for-the-book-demodiversidad-imaginar-nuvens-posibilidades-democraticas-boaventura-sousa-santos-jose-manuel-mendes-ed-akal-2017\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.mariovitoria.com\/participacoes-especiais\/cover-art-for-the-book-demodiversidad-imaginar-nuvens-posibilidades-democraticas-boaventura-sousa-santos-jose-manuel-mendes-ed-akal-2017\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mariovitoria.com\/"},{"@type":"ListItem","position":2,"name":"Cria\u00e7\u00e3o de capa para o Livro Demodiversidad. Imaginar nuvens posibilidades democr\u00e1ticas, Boaventura de Sousa Santos e Jos\u00e9 Manuel Mendes, Ed. Akal"}]},{"@type":"WebSite","@id":"https:\/\/www.mariovitoria.com\/#website","url":"https:\/\/www.mariovitoria.com\/","name":"M\u00e1rio Vit\u00f3ria","description":"Artista Pl\u00e1stico","publisher":{"@id":"https:\/\/www.mariovitoria.com\/#\/schema\/person\/c6a74ef60d3e174cc1af41fabf008e87"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mariovitoria.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/www.mariovitoria.com\/#\/schema\/person\/c6a74ef60d3e174cc1af41fabf008e87","name":"vitoria","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.mariovitoria.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ee633eb0e52b9e9665a034b3c1298ee0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ee633eb0e52b9e9665a034b3c1298ee0?s=96&d=mm&r=g","caption":"vitoria"},"logo":{"@id":"https:\/\/www.mariovitoria.com\/#\/schema\/person\/image\/"}},{"@type":"Person","@id":"https:\/\/www.mariovitoria.com\/#\/schema\/person\/3e39fc7c3dfd691c4f16c3bf2c402146","name":"joana","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.mariovitoria.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/819ee59d51c0110bd6d4581a39403f35?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/819ee59d51c0110bd6d4581a39403f35?s=96&d=mm&r=g","caption":"joana"},"url":"https:\/\/www.mariovitoria.com\/en\/author\/joana\/"}]}},"_links":{"self":[{"href":"https:\/\/www.mariovitoria.com\/en\/wp-json\/wp\/v2\/posts\/3307"}],"collection":[{"href":"https:\/\/www.mariovitoria.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mariovitoria.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mariovitoria.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mariovitoria.com\/en\/wp-json\/wp\/v2\/comments?post=3307"}],"version-history":[{"count":2,"href":"https:\/\/www.mariovitoria.com\/en\/wp-json\/wp\/v2\/posts\/3307\/revisions"}],"predecessor-version":[{"id":3312,"href":"https:\/\/www.mariovitoria.com\/en\/wp-json\/wp\/v2\/posts\/3307\/revisions\/3312"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mariovitoria.com\/en\/wp-json\/wp\/v2\/media\/3311"}],"wp:attachment":[{"href":"https:\/\/www.mariovitoria.com\/en\/wp-json\/wp\/v2\/media?parent=3307"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mariovitoria.com\/en\/wp-json\/wp\/v2\/categories?post=3307"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mariovitoria.com\/en\/wp-json\/wp\/v2\/tags?post=3307"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}